{"id":1608,"date":"2020-05-12T16:35:18","date_gmt":"2020-05-12T21:35:18","guid":{"rendered":"https:\/\/www.docenteconsentido.com\/?p=1608"},"modified":"2020-05-12T16:59:11","modified_gmt":"2020-05-12T21:59:11","slug":"grados-10-y-11-semana-del-11-al-15-de-mayo","status":"publish","type":"post","link":"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/","title":{"rendered":"Grados 10\u00b0 y 11\u00b0 Semana del 11 al 15 de Mayo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1608\" class=\"elementor elementor-1608\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5709648 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5709648\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8894f2d\" data-id=\"8894f2d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-240a41f elementor-widget elementor-widget-text-editor\" data-id=\"240a41f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Cap\u00edtulo 3\u00a0 <span style=\"color: #ff0000;\">ES PARA HOY!!!<\/span><\/h1><p>Hola estudiantes, espero que hoy y siempre est\u00e9n acompa\u00f1ados de mucho amor y salud en la seguridad de sus hogares.<\/p><p>Esta p\u00e1gina es un medio para que nos comuniquemos y recordemos los acuerdos tanto del Proyecto Final, como de compromiso con cada actividad.<\/p><p>En ese orden de ideas\u2026<\/p><h3><span style=\"color: #000080;\">A la fecha de hoy, Mayo 13, deben estar al d\u00eda en las siguientes tareas:<\/span><\/h3><ol><li><strong>Cap\u00edtulo 1 y 2 ya enviados.<\/strong><\/li><li>En el transcurso del d\u00eda de hoy, Mayo 13 enviar el Cap\u00edtulo 3 de su CORTOMETRAJE.<\/li><\/ol><p>De necesitar m\u00e1s tiempo me lo deben hacer saber con justa causa para colocar la nota aprobada.<\/p><h2 style=\"text-align: center;\"><span style=\"color: #000080;\">M\u00e1s ideas para hacer un cap\u00edtulo diferente en tu cortometraje<\/span><\/h2><p>Tenemos el compromiso de ir creando nuestro Cortometraje por cap\u00edtulos\u2026 cada semana me ir\u00e1n entregando un cap\u00edtulo donde tienes total libertad creativa.<\/p><p>A continuaci\u00f3n te mostrar\u00e9 un par de ejemplos que pueden darte ideas a la hora de crear los pr\u00f3ximos cap\u00edtulos por venir.<\/p><h1><span style=\"color: #800080;\">FILMINUTO CON FOTOGRAF\u00cdA<\/span><\/h1><h2>Narrando una historia con secuencia fotogr\u00e1fica.<\/h2><p><iframe src=\"https:\/\/www.youtube.com\/embed\/_daGQ_Y8l7o?rel=0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p><p>Como puedes ver en este ejemplo, hay muchas formas de solucionar la narrativa de un producto audiovisual usando para ello la \u00abSecuencia Fotogr\u00e1fica\u00bb.<\/p><p>Veamos algunos conceptos que deben, a partir de ahora, formar parte de nuestro vocabulario de las artes visuales a la hora de crear y sustentar nuestras creaciones.<\/p><ul><li><h3><span style=\"color: #ff0000;\">Filminuto:<\/span> Es una Mini-Pel\u00edcula que tiene un minuto de duraci\u00f3n, y es creada en plano secuencia (es, precisamente, una secuencia creada sin cortes, con la c\u00e1mara rodando de forma continua, realizando los diferentes tipos de encuadres que se requieran a trav\u00e9s del movimiento o del zoom, si es que esto es necesario.<\/h3><\/li><\/ul><p><iframe src=\"https:\/\/www.youtube.com\/embed\/pb_W-Y7-kcw?rel=0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p><ul><li><h3><span style=\"color: #ff0000;\">Narrativa\u00a0 audiovisual: <\/span>Es una construcci\u00f3n narrativa relatada por una instancia anunciadora o narrador, donde se nos cuenta una historia, y esa historia se nos cuenta desde un punto de vista determinado.<\/h3><\/li><\/ul><p><iframe src=\"https:\/\/www.youtube.com\/embed\/ER36reHyM4s?rel=0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p><ul><li><h3><span style=\"color: #ff0000;\">Secuencia Fotogr\u00e1fica:<\/span> Es una t\u00e9cnica que realiza un secuencia de im\u00e1genes donde el sujeto es capturado en movimiento sucesivo. Esta t\u00e9cnica combina movimiento con una imagen est\u00e1tica, y se vuelve de gran utilidad para la fotograf\u00eda deportiva. Una secuencia fotogr\u00e1fica puede mostrar radicalmente una perspectiva diferente, m\u00e1s interesante quiz\u00e1s que la captura de una \u00fanica imagen. Es posible experimentar el proceso completo de la acci\u00f3n que realiza el atleta.<\/h3><\/li><li><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-1234\" src=\"https:\/\/www.docenteconsentido.com\/wp-content\/uploads\/2020\/05\/6y7.jpg\" alt=\"\" width=\"768\" height=\"602\" srcset=\"https:\/\/aquicreamosweb.com\/arteparatodos\/wp-content\/uploads\/2020\/05\/6y7.jpg 768w, https:\/\/aquicreamosweb.com\/arteparatodos\/wp-content\/uploads\/2020\/05\/6y7-300x235.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/li><\/ul><p>\u00a0<\/p><p>Hoy en d\u00eda la<strong> secuencia fotogr\u00e1fica<\/strong> va desde usar una fotograf\u00eda por evento narrativo hasta el conocido <strong>Stop motion<\/strong>. La diferencia radica en el n\u00famero y sentido de la fotograf\u00eda. En la secuencia fotogr\u00e1fica el artista elige una pose fotogr\u00e1fica, una sola fotograf\u00eda por cada idea, gesto o circunstancia, y que al final con pocas tomas nos presenta una historia. En el <strong>Stop motion<\/strong> se usan m\u00ednimo 24 fotograf\u00edas por segundo de video y narra un periodo de tiempo y movimiento.<\/p><p><iframe src=\"https:\/\/www.youtube.com\/embed\/-heF0LqLieI?rel=0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p><h3>\u00a0<\/h3><h3 style=\"text-align: center;\"><span style=\"color: #000080;\">Manos a la obra y sigue construyendo los cap\u00edtulos de tu Cortometraje.<\/span><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cap\u00edtulo 3\u00a0 ES PARA HOY!!! Hola estudiantes, espero que hoy y siempre est\u00e9n acompa\u00f1ados de mucho amor y salud en la seguridad de sus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1608","post","type-post","status-publish","format-standard","hentry","category-visual-arts-10-y-11"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Grados 10\u00b0 y 11\u00b0 Semana del 11 al 15 de Mayo | Art Class Online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grados 10\u00b0 y 11\u00b0 Semana del 11 al 15 de Mayo | Art Class Online\" \/>\n<meta property=\"og:description\" content=\"Cap\u00edtulo 3\u00a0 ES PARA HOY!!! Hola estudiantes, espero que hoy y siempre est\u00e9n acompa\u00f1ados de mucho amor y salud en la seguridad de sus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/\" \/>\n<meta property=\"og:site_name\" content=\"Art Class Online\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-12T21:35:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-12T21:59:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aquicreamosweb.com\/arteparatodos\/wp-content\/uploads\/2020\/05\/6y7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"602\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diana Carolina Mej\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diana Carolina Mej\u00eda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/\",\"url\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/\",\"name\":\"Grados 10\u00b0 y 11\u00b0 Semana del 11 al 15 de Mayo | Art Class Online\",\"isPartOf\":{\"@id\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.docenteconsentido.com\/wp-content\/uploads\/2020\/05\/6y7.jpg\",\"datePublished\":\"2020-05-12T21:35:18+00:00\",\"dateModified\":\"2020-05-12T21:59:11+00:00\",\"author\":{\"@id\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/#\/schema\/person\/f2bea8960c01428a86530ea39b1093cc\"},\"breadcrumb\":{\"@id\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/#primaryimage\",\"url\":\"https:\/\/www.docenteconsentido.com\/wp-content\/uploads\/2020\/05\/6y7.jpg\",\"contentUrl\":\"https:\/\/www.docenteconsentido.com\/wp-content\/uploads\/2020\/05\/6y7.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grados 10\u00b0 y 11\u00b0 Semana del 11 al 15 de Mayo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/#website\",\"url\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/\",\"name\":\"Art Class Online\",\"description\":\"Un espacio para compartir conocimientos y experiencias a trav\u00e9s de la creaci\u00f3n art\u00edstica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/#\/schema\/person\/f2bea8960c01428a86530ea39b1093cc\",\"name\":\"Diana Carolina Mej\u00eda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe6e9a92132d4f5933aa06642ec92e0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe6e9a92132d4f5933aa06642ec92e0a?s=96&d=mm&r=g\",\"caption\":\"Diana Carolina Mej\u00eda\"},\"url\":\"https:\/\/aquicreamosweb.com\/arteparatodos\/author\/docent\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grados 10\u00b0 y 11\u00b0 Semana del 11 al 15 de Mayo | Art Class Online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/","og_locale":"es_ES","og_type":"article","og_title":"Grados 10\u00b0 y 11\u00b0 Semana del 11 al 15 de Mayo | Art Class Online","og_description":"Cap\u00edtulo 3\u00a0 ES PARA HOY!!! Hola estudiantes, espero que hoy y siempre est\u00e9n acompa\u00f1ados de mucho amor y salud en la seguridad de sus [&hellip;]","og_url":"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/","og_site_name":"Art Class Online","article_published_time":"2020-05-12T21:35:18+00:00","article_modified_time":"2020-05-12T21:59:11+00:00","og_image":[{"width":768,"height":602,"url":"https:\/\/aquicreamosweb.com\/arteparatodos\/wp-content\/uploads\/2020\/05\/6y7.jpg","type":"image\/jpeg"}],"author":"Diana Carolina Mej\u00eda","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Diana Carolina Mej\u00eda","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/","url":"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/","name":"Grados 10\u00b0 y 11\u00b0 Semana del 11 al 15 de Mayo | Art Class Online","isPartOf":{"@id":"https:\/\/aquicreamosweb.com\/arteparatodos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/#primaryimage"},"image":{"@id":"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.docenteconsentido.com\/wp-content\/uploads\/2020\/05\/6y7.jpg","datePublished":"2020-05-12T21:35:18+00:00","dateModified":"2020-05-12T21:59:11+00:00","author":{"@id":"https:\/\/aquicreamosweb.com\/arteparatodos\/#\/schema\/person\/f2bea8960c01428a86530ea39b1093cc"},"breadcrumb":{"@id":"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/#primaryimage","url":"https:\/\/www.docenteconsentido.com\/wp-content\/uploads\/2020\/05\/6y7.jpg","contentUrl":"https:\/\/www.docenteconsentido.com\/wp-content\/uploads\/2020\/05\/6y7.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/aquicreamosweb.com\/arteparatodos\/grados-10-y-11-semana-del-11-al-15-de-mayo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aquicreamosweb.com\/arteparatodos\/"},{"@type":"ListItem","position":2,"name":"Grados 10\u00b0 y 11\u00b0 Semana del 11 al 15 de Mayo"}]},{"@type":"WebSite","@id":"https:\/\/aquicreamosweb.com\/arteparatodos\/#website","url":"https:\/\/aquicreamosweb.com\/arteparatodos\/","name":"Art Class Online","description":"Un espacio para compartir conocimientos y experiencias a trav\u00e9s de la creaci\u00f3n art\u00edstica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aquicreamosweb.com\/arteparatodos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/aquicreamosweb.com\/arteparatodos\/#\/schema\/person\/f2bea8960c01428a86530ea39b1093cc","name":"Diana Carolina Mej\u00eda","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aquicreamosweb.com\/arteparatodos\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe6e9a92132d4f5933aa06642ec92e0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe6e9a92132d4f5933aa06642ec92e0a?s=96&d=mm&r=g","caption":"Diana Carolina Mej\u00eda"},"url":"https:\/\/aquicreamosweb.com\/arteparatodos\/author\/docent\/"}]}},"_links":{"self":[{"href":"https:\/\/aquicreamosweb.com\/arteparatodos\/wp-json\/wp\/v2\/posts\/1608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquicreamosweb.com\/arteparatodos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aquicreamosweb.com\/arteparatodos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aquicreamosweb.com\/arteparatodos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aquicreamosweb.com\/arteparatodos\/wp-json\/wp\/v2\/comments?post=1608"}],"version-history":[{"count":5,"href":"https:\/\/aquicreamosweb.com\/arteparatodos\/wp-json\/wp\/v2\/posts\/1608\/revisions"}],"predecessor-version":[{"id":1617,"href":"https:\/\/aquicreamosweb.com\/arteparatodos\/wp-json\/wp\/v2\/posts\/1608\/revisions\/1617"}],"wp:attachment":[{"href":"https:\/\/aquicreamosweb.com\/arteparatodos\/wp-json\/wp\/v2\/media?parent=1608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aquicreamosweb.com\/arteparatodos\/wp-json\/wp\/v2\/categories?post=1608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aquicreamosweb.com\/arteparatodos\/wp-json\/wp\/v2\/tags?post=1608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}